{"id":7659,"date":"2026-05-11T10:21:26","date_gmt":"2026-05-11T08:21:26","guid":{"rendered":"https:\/\/www.balaton-zeitung.info\/marktplatz\/?post_type=advert&#038;p=7659"},"modified":"2026-05-11T10:21:26","modified_gmt":"2026-05-11T08:21:26","slug":"gebaeudereiniger-sucht-stelle","status":"publish","type":"advert","link":"https:\/\/www.balaton-zeitung.info\/marktplatz\/advert\/gebaeudereiniger-sucht-stelle\/","title":{"rendered":"Geb\u00e4udereiniger sucht Stelle"},"content":{"rendered":"<p>Rentner, im Berufsleben <strong>Geb\u00e4udereiniger<\/strong> gewesen sucht Stelle zum Reinigen von Ferienwohnungen oder H\u00e4usern. In der Umgebung vom Balaton. Spreche leider kein Ungarisch.<\/p>\n<p>E-Mail: <strong>ludwigsburger55@gmail.com<\/strong><\/p>\n","protected":false},"author":2,"template":"","advert_category":[7,81,11],"class_list":["post-7659","classified","type-advert","status-publish","has-post-thumbnail","hentry","advert_category-gesuche","advert_category-reinigung","advert_category-stellenangebote-stellengesuche"],"_links":{"self":[{"href":"https:\/\/www.balaton-zeitung.info\/marktplatz\/wp-json\/wp\/v2\/advert\/7659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.balaton-zeitung.info\/marktplatz\/wp-json\/wp\/v2\/advert"}],"about":[{"href":"https:\/\/www.balaton-zeitung.info\/marktplatz\/wp-json\/wp\/v2\/types\/advert"}],"author":[{"embeddable":true,"href":"https:\/\/www.balaton-zeitung.info\/marktplatz\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.balaton-zeitung.info\/marktplatz\/wp-json\/wp\/v2\/media\/7660"}],"wp:attachment":[{"href":"https:\/\/www.balaton-zeitung.info\/marktplatz\/wp-json\/wp\/v2\/media?parent=7659"}],"wp:term":[{"taxonomy":"advert_category","embeddable":true,"href":"https:\/\/www.balaton-zeitung.info\/marktplatz\/wp-json\/wp\/v2\/advert_category?post=7659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}